{"id":1297,"date":"2024-12-11T09:26:00","date_gmt":"2024-12-11T12:26:00","guid":{"rendered":"https:\/\/materlandia.mg.leg.br\/?p=1297"},"modified":"2024-12-11T21:27:38","modified_gmt":"2024-12-12T00:27:38","slug":"aviso-n-101-2024","status":"publish","type":"post","link":"https:\/\/materlandia.mg.leg.br\/index.php\/2024\/12\/11\/aviso-n-101-2024\/","title":{"rendered":"AVISO N\u00b0 101\/2024"},"content":{"rendered":"\n<p><strong>AVISO DE DISPENSA PARA COTA\u00c7\u00c3O DE PRE\u00c7OS N\u00b0 101\/2024<\/strong><\/p>\n\n\n\n<h1 class=\"wp-block-heading\">&nbsp;OBJETO: Fornecimento de roteador para a C\u00e2mara Municipal de Materl\u00e2ndia.<\/h1>\n\n\n\n<h1 class=\"wp-block-heading\">&nbsp;<\/h1>\n\n\n\n<p>A C\u00c2MARA MUNICIPAL DE MATERL\u00c2NDIA, ESTADO DE MINAS GERAIS, no uso de suas atribui\u00e7\u00f5es legais, considerando a necessidade de promover processos transparentes em face das contrata\u00e7\u00f5es DIRETAS atrav\u00e9s de DISPENSA DE LICITA\u00c7\u00c3O com fundamento no Art. 75, II da Lei N\u00ba 14.133\/21, torna p\u00fablico que realizar\u00e1 Chamamento P\u00fablico para convoca\u00e7\u00e3o de Pessoas Jur\u00eddicas para apresentarem propostas para os produtos supracitados, conforme especifica\u00e7\u00f5es e quantidades estabelecidas abaixo:<\/p>\n\n\n\n<figure class=\"wp-block-table\"><table class=\"has-fixed-layout\"><tbody><tr><td><strong>ITEM<\/strong><\/td><td><strong>PRODUTOS<\/strong><\/td><td><strong>MARCA<\/strong><\/td><td><strong>VALOR<\/strong><\/td><\/tr><tr><td>&nbsp; 01<\/td><td>01 Roteador 2 antenas 300 mbps<\/td><td>&nbsp;<\/td><td>&nbsp;<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<p>Prazo para recebimento de proposta \u00e9 at\u00e9 13\/12\/2024. Atrav\u00e9s do e-mail: <a href=\"mailto:contato@materlandia.mg.leg.br\">contato@materlandia.mg.leg.br<\/a>, WhatsApp (33) 998292782 ou pessoalmente na sede da<\/p>\n\n\n\n<p>C\u00e2mara Municipal de Materl\u00e2ndia.<\/p>\n\n\n\n<p><strong>AOS INTERESSADOS:<\/strong><\/p>\n\n\n\n<p>A PROPOSTA \u00c0 PRESENTE COTA\u00c7\u00c3O DE PRE\u00c7OS DEVER\u00c1 CONTER OS DADOS ESPECIFICADOS ABAIXO:<\/p>\n\n\n\n<p>b) CNPJ e Raz\u00e3o Social do estabelecimento\/empresa\/prestador;<\/p>\n\n\n\n<p>&nbsp;c) Endere\u00e7o completo do estabelecimento\/empresa\/prestador;<\/p>\n\n\n\n<p>d) Telefones de contato, e n\u00famero de Fax, se houver;<\/p>\n\n\n\n<p>e) Endere\u00e7o Eletr\u00f4nico (e-MAIL);<\/p>\n\n\n\n<p>f) Prazo de validade da proposta de pre\u00e7os (m\u00ednimo de 60 dias);<\/p>\n\n\n\n<p>g) Nome, carimbo e assinatura de representante e\/ou respons\u00e1vel pela proposta de pre\u00e7os apresentada;<\/p>\n\n\n\n<p>h) TODOS OS PRODUTOS PROPOSTOS DEVER\u00c3O CONTER A INDICA\u00c7\u00c3O DE MARCA E MODELO OFERTADO, E ATENDER \u00c0 DESCRI\u00c7\u00c3O E ESPECIFICA\u00c7\u00d5ES NESTE DOCUMENTO<\/p>\n\n\n\n<p>OBSERVA\u00c7\u00c3O: Para todos os pre\u00e7os e valores propostos, entende-se estarem inclusos os custos, impostos e fretes (Pre\u00e7o CIF). Solicitamos, por gentileza, que nos seja dado <strong><u>retorno<\/u><\/strong> <strong>no prazo m\u00e1ximo de 03 dias \u00fateis.<\/strong><\/p>\n\n\n\n<p><strong>MODELO PROPOSTA DE PRE\u00c7OS<\/strong><\/p>\n\n\n\n<p>&nbsp;RAZ\u00c3O SOCIAL: _______________________________________________<\/p>\n\n\n\n<p>&nbsp;CNPJ: ___________________\/_______&nbsp;&nbsp;&nbsp; Tel.: (____) __________-________<\/p>\n\n\n\n<p>E-mail: ________________________________________________________<\/p>\n\n\n\n<p>Endere\u00e7o:______________________________________________________<\/p>\n\n\n\n<p>Respons\u00e1vel:____________________________________________________<\/p>\n\n\n\n<p>Apresentamos a presente proposta de pre\u00e7os, observadas as condi\u00e7\u00f5es e especifica\u00e7\u00f5es recebidas, v\u00e1lida por 60 (sessenta) dias, a contar desta data, na forma de simples cota\u00e7\u00e3o realizada pela C\u00c2MARA MUNICIPAL DE MATERL\u00c2NDIA-MG, inscrita no CNPJ sob o N\u00ba. 03.049.124\/0001-50, referente ao Processo de Dispensa de Licita\u00e7\u00e3o n\u00b0 101\/2024.<\/p>\n\n\n\n<p>Materl\u00e2ndia MG, 10 de dezembro de 2024.<\/p>\n\n\n\n<p>Agente de Contrata\u00e7\u00e3o \u2013 Rosinea Souza Santos Correa<\/p>\n\n\n\n<p>Equipe de Apoio \u2013 Mariza Moura da Fonseca Ambrosio<\/p>\n\n\n\n<div data-wp-interactive=\"core\/file\" class=\"wp-block-file\"><object data-wp-bind--hidden=\"!state.hasPdfPreview\" hidden class=\"wp-block-file__embed\" data=\"https:\/\/materlandia.mg.leg.br\/wp-content\/uploads\/2024\/12\/AVISO-N1012024.pdf\" type=\"application\/pdf\" style=\"width:100%;height:600px\" aria-label=\"Incorporado de AVISO N1012024.\"><\/object><a id=\"wp-block-file--media-cee6142e-ec38-4be2-9014-9bd2288e1d5d\" href=\"https:\/\/materlandia.mg.leg.br\/wp-content\/uploads\/2024\/12\/AVISO-N1012024.pdf\">AVISO N1012024<\/a><a href=\"https:\/\/materlandia.mg.leg.br\/wp-content\/uploads\/2024\/12\/AVISO-N1012024.pdf\" class=\"wp-block-file__button wp-element-button\" download aria-describedby=\"wp-block-file--media-cee6142e-ec38-4be2-9014-9bd2288e1d5d\">Baixar<\/a><\/div>\n","protected":false},"excerpt":{"rendered":"<p>AVISO DE DISPENSA PARA COTA\u00c7\u00c3O DE PRE\u00c7OS N\u00b0 101\/2024 &nbsp;OBJETO: Fornecimento de roteador para a C\u00e2mara Municipal de Materl\u00e2ndia. &nbsp; A C\u00c2MARA MUNICIPAL DE MATERL\u00c2NDIA, ESTADO DE MINAS GERAIS, no uso de suas atribui\u00e7\u00f5es legais, considerando a necessidade de promover processos transparentes em face das contrata\u00e7\u00f5es DIRETAS atrav\u00e9s de DISPENSA DE LICITA\u00c7\u00c3O com fundamento no [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"templates\/template-full-width.php","format":"standard","meta":{"footnotes":""},"categories":[1,8],"tags":[],"class_list":["post-1297","post","type-post","status-publish","format-standard","hentry","category-noticias","category-processo-seletivo"],"_links":{"self":[{"href":"https:\/\/materlandia.mg.leg.br\/index.php\/wp-json\/wp\/v2\/posts\/1297","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/materlandia.mg.leg.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/materlandia.mg.leg.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/materlandia.mg.leg.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/materlandia.mg.leg.br\/index.php\/wp-json\/wp\/v2\/comments?post=1297"}],"version-history":[{"count":1,"href":"https:\/\/materlandia.mg.leg.br\/index.php\/wp-json\/wp\/v2\/posts\/1297\/revisions"}],"predecessor-version":[{"id":1299,"href":"https:\/\/materlandia.mg.leg.br\/index.php\/wp-json\/wp\/v2\/posts\/1297\/revisions\/1299"}],"wp:attachment":[{"href":"https:\/\/materlandia.mg.leg.br\/index.php\/wp-json\/wp\/v2\/media?parent=1297"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/materlandia.mg.leg.br\/index.php\/wp-json\/wp\/v2\/categories?post=1297"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/materlandia.mg.leg.br\/index.php\/wp-json\/wp\/v2\/tags?post=1297"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}